{"id":105,"date":"2025-11-07T11:27:33","date_gmt":"2025-11-07T03:27:33","guid":{"rendered":"http:\/\/localhost\/?post_type=acf-field&#038;p=644"},"modified":"2026-02-09T09:27:21","modified_gmt":"2026-02-09T01:27:21","slug":"modern-large-office-desk-with-bookshelf-and-tower-shelf-2","status":"publish","type":"products","link":"https:\/\/www.homefurnitureliving.com\/de\/products\/modern-large-office-desk-with-bookshelf-and-tower-shelf-2\/","title":{"rendered":"Moderner gro\u00dfer B\u00fcrotisch mit B\u00fccherregal und Turmregal"},"content":{"rendered":"<ul>\n<li>Ger\u00e4umiger Arbeitsbereich: Das Ma\u00df von 110,0 cm (L) x 55,1 cm (B) x 134,9 cm (H) bietet ausreichend Platz f\u00fcr Ihren Laptop, PC, Tastatur und Schreibtischzubeh\u00f6r. Zudem bietet er gen\u00fcgend Raum f\u00fcr eine Gaming-Setup, Papierarbeiten sowie andere B\u00fcroaktivit\u00e4ten.<img decoding=\"async\" alt=\"\" src=\"https:\/\/www.homefurnitureliving.com\/wp-content\/uploads\/2025\/10\/3.effectsResult_79654f1f-b736-49b1-a285-fe8ab481c20f_480x480.jpg\" style=\"font-size: 0.875rem; color: #0f1111; background-color: #ffffff; font-family: 'Amazon Ember', Arial, sans-serif;\" data-mce-fragment=\"1\" data-no-translation=\"\" \/><\/li>\n<li>Organisieren Sie Ihren Arbeitsplatz: Mit 2-stufigen Ablageb\u00f6den rechts und einem offenen B\u00fccherregal unter dem Schreibtisch gibt es viel Stauraum f\u00fcr Akten, B\u00fccher und B\u00fcrobedarf \u2013 so halten Sie das Wesentliche stets griffbereit. Das untere Regal rechts ist gro\u00df genug, um Ihren Computerhost zu platzieren.<\/li>\n<li><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.homefurnitureliving.com\/wp-content\/uploads\/2025\/10\/6.effectsResult_6f10c673-ce0c-4da5-8776-ccace8573040_480x480.jpg\" style=\"font-size: 0.875rem; color: #0f1111; background-color: #ffffff; font-family: 'Amazon Ember', Arial, sans-serif;\" data-mce-fragment=\"1\" data-no-translation=\"\" \/><\/li>\n<li>Extrem langlebig und stabil: Der Home-Office-Schreibtisch besteht aus MDF-Platte mit stabilem Stahlrahmen. Die MDF-Platte ist wasser- und staubbest\u00e4ndig und leicht zu reinigen. Die F\u00fc\u00dfe verhindern nicht nur Kratzer auf unebenem Boden und sorgen f\u00fcr zus\u00e4tzliche Stabilit\u00e4t, sondern erm\u00f6glichen auch die H\u00f6henverstellung, um unterschiedlichen Anforderungen gerecht zu werden.<\/li>\n<li>Multifunktionaler 3-in-1-Schreibtisch: Dank seines kompakten Designs passt dieser Schreibtisch perfekt in kleine R\u00e4ume und maximiert optimal Ihren Home-Office-Arbeitsplatz. Er eignet sich hervorragend f\u00fcr Arbeitszimmer, Schlafzimmer, Wohnzimmer und B\u00fcro und kann als Computertisch, B\u00fcroarbeitsplatz, Studiertisch, Schreibtisch oder Gaming-Tisch genutzt werden.<\/li>\n<li>Einfache Montage: Alle ben\u00f6tigten Teile, Werkzeuge und Anleitungen sind im Lieferumfang enthalten. Bei Fragen stehen wir Ihnen selbstverst\u00e4ndlich gerne zur Verf\u00fcgung.<img decoding=\"async\" alt=\"\" src=\"https:\/\/www.homefurnitureliving.com\/wp-content\/uploads\/2025\/10\/7.effectsResult_fc4e2e5e-da2f-4e5f-aaa0-1f73feb97237_480x480.jpg\" style=\"font-size: 0.875rem; color: #0f1111; background-color: #ffffff; font-family: 'Amazon Ember', Arial, sans-serif;\" data-mce-fragment=\"1\" data-no-translation=\"\" \/><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>21,7\u2033D x 43,3\u2033W x 53,1\u2033H<\/p>","protected":false},"featured_media":842,"template":"","adweb_product_categories":[136],"adweb_product_tags":[153,190,191],"class_list":["post-105","products","type-products","status-publish","has-post-thumbnail","hentry","adweb_product_cat-computer-desk","adweb_product_tag-modern-large-office-desk","adweb_product_tag-with-bookshelf","adweb_product_tag-with-tower-shelf"],"gallery":[842,845,849],"order":null,"acf":[],"_links":{"self":[{"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/adweb_products\/105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/adweb_products"}],"about":[{"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/media\/842"}],"wp:attachment":[{"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/media?parent=105"}],"wp:term":[{"taxonomy":"adweb_product_cat","embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/adweb_product_categories?post=105"},{"taxonomy":"adweb_product_tag","embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/adweb_product_tags?post=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}