{"id":8434,"date":"2025-11-07T11:26:03","date_gmt":"2025-11-07T03:26:03","guid":{"rendered":"https:\/\/www.homefurnitureliving.com\/products\/4-shelves-bookcase-display-stand-wood-magazine-rack-file-storage-holder\/"},"modified":"2026-02-09T14:24:21","modified_gmt":"2026-02-09T06:24:21","slug":"4-shelves-bookcase-display-stand-wood-magazine-rack-file-storage-holder","status":"publish","type":"products","link":"https:\/\/www.homefurnitureliving.com\/de\/products\/4-shelves-bookcase-display-stand-wood-magazine-rack-file-storage-holder\/","title":{"rendered":"4 Regale B\u00fccherregal Ausstellungsst\u00e4nder Holz Zeitschriftenhalter Aktenaufbewahrungshalter"},"content":{"rendered":"<ul>\n<li>Langlebig: Diese Einheit besteht aus 1,2 cm dickem MDF. Mit einer robusten UV-Lackierung ist dieses St\u00fcck \u00e4u\u00dferst kratz- und fleckenbest\u00e4ndig. Zehenkappen verhindern, dass kleine Gegenst\u00e4nde darunterrollen.<\/li>\n<li>Lesen in Reichweite: Das B\u00fccherregal verf\u00fcgt \u00fcber 4 breite F\u00e4cher, die in der perfekten H\u00f6he angebracht sind, sodass Kinder und Kleinkinder ihre Lieblingsb\u00fccher in einem Klassenzimmer, Kindertagesst\u00e4tte, Spielzimmer oder Zuhause problemlos sehen und erreichen k\u00f6nnen.<\/li>\n<li>Gesamtabmessung: Misst Gr\u00f6\u00dfe: 50 x 24 x 47 cm; Perfekte Gr\u00f6\u00dfe f\u00fcr Wohnzimmer, Esszimmer, Schlafzimmer, Flur und Eingangsbereich \u2013 ideal f\u00fcr Zuhause, B\u00fcro und Schule.<\/li>\n<li>Lokaler Service: Das Produkt liegt in US-Warenlagern vor und kann innerhalb von 2\u20135 Tagen geliefert werden. Bei Unzufriedenheit mit unserem Produkt erhalten Sie problemlos kostenlos R\u00fccksendungen. Unsere 24\/7-Kundenservice-Hotline steht Ihnen jederzeit zur Verf\u00fcgung.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Wei\u00df<\/p>","protected":false},"featured_media":3554,"template":"","adweb_product_categories":[108],"adweb_product_tags":[231,229,230],"class_list":["post-8434","products","type-products","status-publish","has-post-thumbnail","hentry","adweb_product_cat-bookshelves","adweb_product_tag-bookcase-display-stand","adweb_product_tag-file-storage-holder","adweb_product_tag-wood-magazine-rack"],"gallery":[3554,3569,3591,3615,3629,3648,3663],"order":null,"acf":[],"_links":{"self":[{"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/adweb_products\/8434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/adweb_products"}],"about":[{"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/media\/3554"}],"wp:attachment":[{"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/media?parent=8434"}],"wp:term":[{"taxonomy":"adweb_product_cat","embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/adweb_product_categories?post=8434"},{"taxonomy":"adweb_product_tag","embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/adweb_product_tags?post=8434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}