{"id":87,"date":"2025-11-07T11:27:00","date_gmt":"2025-11-07T03:27:00","guid":{"rendered":"http:\/\/localhost\/?post_type=acf-field&#038;p=8990"},"modified":"2026-02-09T10:47:41","modified_gmt":"2026-02-09T02:47:41","slug":"31-5-inch-modern-study-writing-desk-with-storage-shelves-4","status":"publish","type":"products","link":"https:\/\/www.homefurnitureliving.com\/de\/products\/31-5-inch-modern-study-writing-desk-with-storage-shelves-4\/","title":{"rendered":"31,5 Zoll moderner Schreibtisch mit Ablagef\u00e4chern"},"content":{"rendered":"<ul>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">Intelligenter &amp; stilvoller Schreibtisch: Das schlichte, stilvolle Design ist perfekt f\u00fcr ein Schlafzimmer, ein Heimb\u00fcro, eine kleine Wohnung oder ein Studentenzimmer. Er dient als Schreib- und Computertisch und bietet ausreichend Arbeitsfl\u00e4che f\u00fcr Computer und Monitore im Arbeitszimmer.<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">Dicke aber stabile Konstruktion: Hergestellt aus MDF und Metallmaterial, verf\u00fcgt er \u00fcber eine dicke Tischplatte sowie eine robuste Konstruktion aus hochbelastbarem, pulverbeschichtetem Stahl, die Ihnen Stabilit\u00e4t und Langlebigkeit garantiert. Zudem erm\u00f6glicht er es Ihnen, Ihr Zuhause oder B\u00fcro aufzur\u00e4umen und erleichtert das Auffinden Ihrer ben\u00f6tigten Dinge.<\/span><span class=\"a-list-item\"><\/span><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>19.69\u2033D x 31.5\u2033W x 29.53\u2033H<\/p>","protected":false},"featured_media":2695,"template":"","adweb_product_categories":[136],"adweb_product_tags":[206,155],"class_list":["post-87","products","type-products","status-publish","has-post-thumbnail","hentry","adweb_product_cat-computer-desk","adweb_product_tag-modern-study-writing-desk","adweb_product_tag-with-storage-shelves"],"gallery":[2695,2712,2728,2742],"order":null,"acf":[],"_links":{"self":[{"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/adweb_products\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/adweb_products"}],"about":[{"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/media\/2695"}],"wp:attachment":[{"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/media?parent=87"}],"wp:term":[{"taxonomy":"adweb_product_cat","embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/adweb_product_categories?post=87"},{"taxonomy":"adweb_product_tag","embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/de\/wp-json\/wp\/v2\/adweb_product_tags?post=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}