{"id":111,"date":"2025-11-07T11:27:35","date_gmt":"2025-11-07T03:27:35","guid":{"rendered":"https:\/\/www.homefurnitureliving.com\/?post_type=wpcode&#038;p=111"},"modified":"2026-02-06T17:31:04","modified_gmt":"2026-02-06T09:31:04","slug":"home-office-computer-desk-writing-study-desk-book-writing-corner-table-4","status":"publish","type":"products","link":"https:\/\/www.homefurnitureliving.com\/it\/products\/home-office-computer-desk-writing-study-desk-book-writing-corner-table-4\/","title":{"rendered":"Home Office Scrivania per computer Scrivania per studio Scrivania per libri Tavolo d'angolo per scrittura"},"content":{"rendered":"<ul>\n<li>IDEALE PER LO STUDIO DOMESTICO E GLI SPAZI DI LAVORO: Questa scrivania \u00e8 elegante, ma allo stesso tempo semplice e robusta. Con il suo design a concetto aperto e l'estetica pulita, questa scrivania per computer rappresenta la scelta perfetta per qualsiasi ufficio o spazio di lavoro.<img decoding=\"async\" src=\"https:\/\/www.homefurnitureliving.com\/wp-content\/uploads\/2025\/10\/f0b4de7b0255f3400b7524098cb294b0_ba7e8c75-9d1c-4cf0-886b-d6753addfe0a_480x480.jpg\" alt=\"\" data-mce-fragment=\"1\" data-no-translation=\"\" \/><\/li>\n<li>CAMPO D'APPLICAZIONE: Adatto per studio, camera da letto, soggiorno, cucina, stanza dei bambini e ufficio. Pu\u00f2 essere utilizzato come scrivania per computer, tavoli per l'apprendimento, tavoli da gioco, tavoli da picnic, scrivanie direzionali, per camera da letto, studio, ecc.; il prodotto \u00e8 stato sottoposto a rigorosi test, sopportando un certo peso o rimanendo posizionato per un periodo di tempo senza deformarsi n\u00e9 piegarsi.<img decoding=\"async\" src=\"https:\/\/www.homefurnitureliving.com\/wp-content\/uploads\/2025\/10\/a7b86b01fc62d9577ae00825235fc112_2922e281-2ea3-4f99-beeb-bffacf5c7d50_480x480.jpg\" alt=\"\" data-mce-fragment=\"1\" data-no-translation=\"\" \/><\/li>\n<li>MATERIALE DI ALTA QUALIT\u00c0: La struttura complessiva \u00e8 stabile, il piano di lavoro \u00e8 resistente all'usura, ai graffi, impermeabile e privo di odori. Supporta fino a 50 kg<\/li>\n<li>DIMENSIONI DELLA SCRIVANIA: 29,53 \u00d7 17,72 \u00d7 29,92 pollici, DIMENSIONI DEL SUPPORTO PER MONITOR: 11,73 \u00d7 5,83 \u00d7 3,03 pollici. Facile da montare con le istruzioni e l'hardware forniti<img decoding=\"async\" src=\"https:\/\/www.homefurnitureliving.com\/wp-content\/uploads\/2025\/10\/468ef44610c31b5b50b747b4f9f5ee49_76a052b2-7993-48f5-a5a2-3b3ea81272ba_480x480.jpg\" alt=\"\" data-mce-fragment=\"1\" data-no-translation=\"\" \/><\/li>\n<li>SERVIZIO CLIENTI DI QUALIT\u00c0: Se avete domande sui nostri scranni, non esitate a contattarci; vi offriremo servizi senza preoccupazioni che vi soddisferanno pienamente.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>17,7\u2033P x 29,5\u2033L x 30\u2033H<\/p>","protected":false},"featured_media":784,"template":"","adweb_product_categories":[136],"adweb_product_tags":[161,175,162],"class_list":["post-111","products","type-products","status-publish","has-post-thumbnail","hentry","adweb_product_cat-computer-desk","adweb_product_tag-home-office-computer-desk","adweb_product_tag-writing-corner-table","adweb_product_tag-writing-study-desk"],"gallery":[784,785],"order":null,"acf":[],"_links":{"self":[{"href":"https:\/\/www.homefurnitureliving.com\/it\/wp-json\/wp\/v2\/adweb_products\/111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.homefurnitureliving.com\/it\/wp-json\/wp\/v2\/adweb_products"}],"about":[{"href":"https:\/\/www.homefurnitureliving.com\/it\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/it\/wp-json\/wp\/v2\/media\/784"}],"wp:attachment":[{"href":"https:\/\/www.homefurnitureliving.com\/it\/wp-json\/wp\/v2\/media?parent=111"}],"wp:term":[{"taxonomy":"adweb_product_cat","embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/it\/wp-json\/wp\/v2\/adweb_product_categories?post=111"},{"taxonomy":"adweb_product_tag","embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/it\/wp-json\/wp\/v2\/adweb_product_tags?post=111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}