{"id":8447,"date":"2025-11-07T11:26:06","date_gmt":"2025-11-07T03:26:06","guid":{"rendered":"https:\/\/www.homefurnitureliving.com\/products\/narrow-bookshelf-6-tier-industrial-bookcase-rustic-open-book-shelf-freestanding-horizontal-bookshelves-with-metal-frame\/"},"modified":"2026-02-09T13:59:00","modified_gmt":"2026-02-09T05:59:00","slug":"narrow-bookshelf-6-tier-industrial-bookcase-rustic-open-book-shelf-freestanding-horizontal-bookshelves-with-metal-frame","status":"publish","type":"products","link":"https:\/\/www.homefurnitureliving.com\/it\/products\/narrow-bookshelf-6-tier-industrial-bookcase-rustic-open-book-shelf-freestanding-horizontal-bookshelves-with-metal-frame\/","title":{"rendered":"Scaffale per Libri Sottile, Libreria Industriale a 6 Ripiani, Scaffale Aperto Rustico, Scaffali per Libri Orizzontali Autoportanti con Struttura in Metallo"},"content":{"rendered":"<ul>\n<li>Robusta e facile da pulire: i piedi possono essere regolati per garantire che il ripiano rimanga stabile, ed \u00e8 semplice da pulire con solo uno straccio.<\/li>\n<li>Durevole ed ecologica: il nostro ripiano verticale \u00e8 realizzato in MDF di alta qualit\u00e0 e metallo di prima scelta, ed \u00e8 conforme allo standard US CARB P2, quindi non devi preoccuparti di cattivi odori.<\/li>\n<li>Facile da montare: con il suo stile scandinavo, questo ripiano si abbina a tutti gli altri tuoi mobili ed \u00e8 facile da assemblare, richiedendo soltanto 20 minuti.<\/li>\n<li><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.homefurnitureliving.com\/wp-content\/uploads\/2025\/10\/ad82006b8a634102b5aff0abfa4e164f_tplv-aphluv4xwc-origin-jpeg.jpg\" data-no-translation=\"\" \/><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.homefurnitureliving.com\/wp-content\/uploads\/2025\/10\/b7d37775aec24596bcffaec29faeab50_tplv-aphluv4xwc-origin-jpeg.jpg\" data-no-translation=\"\" \/><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Scaffale per Libri Sottile, Libreria Industriale a 6 Ripiani, Scaffale Aperto Rustico, Scaffali per Libri Orizzontali Autoportanti con Struttura in Metallo<\/p>","protected":false},"featured_media":6283,"template":"","adweb_product_categories":[108],"adweb_product_tags":[228,226,225,227,224],"class_list":["post-8447","products","type-products","status-publish","has-post-thumbnail","hentry","adweb_product_cat-bookshelves","adweb_product_tag-freestanding-horizontal-bookshelves","adweb_product_tag-industrial-bookcase","adweb_product_tag-narrow-bookshelf","adweb_product_tag-rustic-open-book-shelf","adweb_product_tag-with-metal-frame"],"gallery":[6283,6293,6303,6314,6323],"order":null,"acf":[],"_links":{"self":[{"href":"https:\/\/www.homefurnitureliving.com\/it\/wp-json\/wp\/v2\/adweb_products\/8447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.homefurnitureliving.com\/it\/wp-json\/wp\/v2\/adweb_products"}],"about":[{"href":"https:\/\/www.homefurnitureliving.com\/it\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/it\/wp-json\/wp\/v2\/media\/6283"}],"wp:attachment":[{"href":"https:\/\/www.homefurnitureliving.com\/it\/wp-json\/wp\/v2\/media?parent=8447"}],"wp:term":[{"taxonomy":"adweb_product_cat","embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/it\/wp-json\/wp\/v2\/adweb_product_categories?post=8447"},{"taxonomy":"adweb_product_tag","embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/it\/wp-json\/wp\/v2\/adweb_product_tags?post=8447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}