{"id":8434,"date":"2025-11-07T11:26:03","date_gmt":"2025-11-07T03:26:03","guid":{"rendered":"https:\/\/www.homefurnitureliving.com\/products\/4-shelves-bookcase-display-stand-wood-magazine-rack-file-storage-holder\/"},"modified":"2026-02-09T14:24:21","modified_gmt":"2026-02-09T06:24:21","slug":"4-shelves-bookcase-display-stand-wood-magazine-rack-file-storage-holder","status":"publish","type":"products","link":"https:\/\/www.homefurnitureliving.com\/pt\/products\/4-shelves-bookcase-display-stand-wood-magazine-rack-file-storage-holder\/","title":{"rendered":"Estante de Livros com 4 Prateleiras, Suporte de Exibi\u00e7\u00e3o, Rack de Madeira para Revistas e Armazenamento de Arquivos"},"content":{"rendered":"<ul>\n<li>Dur\u00e1vel: Esta unidade \u00e9 constru\u00edda em MDF com 1,2 cm de espessura. Com um resistente acabamento UV, esta pe\u00e7a \u00e9 extremamente resistente a riscos e manchas. Os rodap\u00e9s evitam que pequenos objetos rolem para debaixo dela.<\/li>\n<li>Leitura ao Alcance: A estante possui 4 espa\u00e7os amplos posicionados na altura perfeita para permitir que crian\u00e7as e beb\u00eas vejam e alcancem seus livros favoritos em sala de aula, creche, brinquedoteca ou em casa<\/li>\n<li>Dimens\u00e3o Geral: Mede 19,7 x 9,5 x 18,5 polegadas; tamanho perfeito para sala de estar, sala de jantar, quarto, corredor e entrada, \u00f3timo para casa, escrit\u00f3rio e escola.<\/li>\n<li>Atendimento Local: O produto est\u00e1 armazenado em dep\u00f3sitos nos EUA e pode ser entregue em 2 a 5 dias. Devolu\u00e7\u00e3o gratuita facilitada caso voc\u00ea n\u00e3o esteja satisfeito com nosso produto. Atendimento ao cliente 24 horas por dia, 7 dias por semana, \u00e0 sua disposi\u00e7\u00e3o.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Branco<\/p>","protected":false},"featured_media":3554,"template":"","adweb_product_categories":[108],"adweb_product_tags":[231,229,230],"class_list":["post-8434","products","type-products","status-publish","has-post-thumbnail","hentry","adweb_product_cat-bookshelves","adweb_product_tag-bookcase-display-stand","adweb_product_tag-file-storage-holder","adweb_product_tag-wood-magazine-rack"],"gallery":[3554,3569,3591,3615,3629,3648,3663],"order":null,"acf":[],"_links":{"self":[{"href":"https:\/\/www.homefurnitureliving.com\/pt\/wp-json\/wp\/v2\/adweb_products\/8434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.homefurnitureliving.com\/pt\/wp-json\/wp\/v2\/adweb_products"}],"about":[{"href":"https:\/\/www.homefurnitureliving.com\/pt\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/pt\/wp-json\/wp\/v2\/media\/3554"}],"wp:attachment":[{"href":"https:\/\/www.homefurnitureliving.com\/pt\/wp-json\/wp\/v2\/media?parent=8434"}],"wp:term":[{"taxonomy":"adweb_product_cat","embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/pt\/wp-json\/wp\/v2\/adweb_product_categories?post=8434"},{"taxonomy":"adweb_product_tag","embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/pt\/wp-json\/wp\/v2\/adweb_product_tags?post=8434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}