{"id":8437,"date":"2025-11-07T11:26:04","date_gmt":"2025-11-07T03:26:04","guid":{"rendered":"https:\/\/www.homefurnitureliving.com\/products\/2-cube-bookcase-display-bookshelf-for-living-room-bedroom-home\/"},"modified":"2026-02-09T14:17:29","modified_gmt":"2026-02-09T06:17:29","slug":"2-cube-bookcase-display-bookshelf-for-living-room-bedroom-home","status":"publish","type":"products","link":"https:\/\/www.homefurnitureliving.com\/pt\/products\/2-cube-bookcase-display-bookshelf-for-living-room-bedroom-home\/","title":{"rendered":"Estante Expositora de Livros 2 Cubos para Sala de Estar, Quarto e Casa"},"content":{"rendered":"<ul>\n<li>PARA PEQUENOS ESPA\u00c7OS - A estante de livros compacta de 2 cubos foi projetada para ser colocada e utilizada em pequenos espa\u00e7os, garantindo o uso mais eficiente do espa\u00e7o, especialmente adequada para qualquer canto apertado da sua casa.<\/li>\n<li>SIMPLICIDADE MODERNA - Com estilo minimalista de linhas, cria um visual limpo e elegante. Dispon\u00edvel em cores ricas, \u00e9 ideal para decora\u00e7\u00f5es boho, r\u00fasticas, tradicionais, cl\u00e1ssicas ou modernas, combinando perfeitamente com qualquer estilo de decora\u00e7\u00e3o e mobili\u00e1rio dom\u00e9stico.<\/li>\n<li>USO MULTIFUNCIONAL - 11,8\u2033 x 11,8\u2033 x 23,62\u2033 (C x L x A). Esta estante de livros com 2 n\u00edveis pode ser usada como uma prateleira vertical ou horizontal, criado-mudo, mesa de caf\u00e9 ou mesa lateral. Os pain\u00e9is espessos de MDF de 12 mm s\u00e3o perfeitos para armazenar livros grandes, revistas, plantas e at\u00e9 mesmo x\u00edcaras de caf\u00e9. Observar que podem haver diferen\u00e7as de 1 a 3 cm nas medidas manuais.<img decoding=\"async\" data-mce-fragment=\"1\" alt=\"\" src=\"https:\/\/www.homefurnitureliving.com\/wp-content\/uploads\/2025\/10\/2_c564ca76-1f1d-4f70-af08-4929b0_480x480.jpg\" data-no-translation=\"\" \/><\/li>\n<li>EXECU\u00c7\u00c3O EXCEPCIONAL - As prateleiras abertas desta estante s\u00e3o feitas de MDF dur\u00e1vel com espessura de 12 mm, o que aumenta a estabilidade geral e oferece excelente capacidade de suporte de carga (cada cubo suporta at\u00e9 13,6 kg). F\u00e1cil de montar. Limpe com um pano seco.<\/li>\n<li>COMBINA\u00c7\u00c3O UNIVERSAL - Utilizada como uma pequena estante-c\u00f4moda para exibir suas cole\u00e7\u00f5es favoritas. Esta estante de madeira pode ser usada em diferentes ambientes: quarto, sala de estar, escrit\u00f3rio, biblioteca, cozinha, restaurante, para decorar sua casa.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Branco<\/p>","protected":false},"featured_media":4069,"template":"","adweb_product_categories":[108],"adweb_product_tags":[233,174],"class_list":["post-8437","products","type-products","status-publish","has-post-thumbnail","hentry","adweb_product_cat-bookshelves","adweb_product_tag-bookcase-display-bookshelf","adweb_product_tag-for-living-room-bedroom-home"],"gallery":[4069,4081,4090,4106,4123,4137,4147],"order":null,"acf":[],"_links":{"self":[{"href":"https:\/\/www.homefurnitureliving.com\/pt\/wp-json\/wp\/v2\/adweb_products\/8437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.homefurnitureliving.com\/pt\/wp-json\/wp\/v2\/adweb_products"}],"about":[{"href":"https:\/\/www.homefurnitureliving.com\/pt\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/pt\/wp-json\/wp\/v2\/media\/4069"}],"wp:attachment":[{"href":"https:\/\/www.homefurnitureliving.com\/pt\/wp-json\/wp\/v2\/media?parent=8437"}],"wp:term":[{"taxonomy":"adweb_product_cat","embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/pt\/wp-json\/wp\/v2\/adweb_product_categories?post=8437"},{"taxonomy":"adweb_product_tag","embeddable":true,"href":"https:\/\/www.homefurnitureliving.com\/pt\/wp-json\/wp\/v2\/adweb_product_tags?post=8437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}